{"id":5131,"date":"2013-05-21T19:26:34","date_gmt":"2013-05-22T02:26:34","guid":{"rendered":"http:\/\/paratodos.com\/pt\/?p=5131"},"modified":"2013-05-21T19:26:34","modified_gmt":"2013-05-22T02:26:34","slug":"paulina-rubio-se-une-a-la-tercera-temporada-de-the-x-factor","status":"publish","type":"post","link":"http:\/\/paratodos.com\/pt\/paulina-rubio-se-une-a-la-tercera-temporada-de-the-x-factor\/","title":{"rendered":"Paulina Rubio se une a la tercera temporada de &#8220;The X Factor&#8221;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-5132\" title=\"paulina-rubio-demi-lovato-the-x-factor-usa\" src=\"http:\/\/paratodos.com\/pt\/wp-content\/uploads\/2013\/05\/paulina-rubio-demi-lovato-the-x-factor-usa.jpg\" alt=\"\" width=\"450\" height=\"370\" srcset=\"http:\/\/paratodos.com\/pt\/wp-content\/uploads\/2013\/05\/paulina-rubio-demi-lovato-the-x-factor-usa.jpg 450w, http:\/\/paratodos.com\/pt\/wp-content\/uploads\/2013\/05\/paulina-rubio-demi-lovato-the-x-factor-usa-300x246.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>La chica dorada se une a uno de los programas mas famosos en la televisi\u00f3n en ingles, The X Factor. Simon Cowell estar\u00e1 rodeado de mujeres en la tercera temporada del programa The X Factor con las nuevas jueces Paulina Rubio y Kelly Rowland. <em>\u201cMe ha tomado m\u00e1s de una d\u00e9cada, pero estoy encantado de estar por fin en un panel con tres chicas (creo!). Paulina y Kelly tienen excelente gusto y gran experiencia en la industria de la m\u00fasica y junto a Demi, se convertir\u00e1n en un grupo muy divertido. Siento que \u00e9ste es el momento de hacer algo diferente\u201d<\/em> comparti\u00f3 Simon Cowell.<\/p>\n<p><em>\u201cMe encanta The X Factor! Estoy muy emocionada de formar parte de la mesa de jurado y de encontrar a la nueva estrella de la m\u00fasica. Simon; cuidado con lo que deseas\u2026vamos a ver si verdaderamente est\u00e1s listo para mi, empieza la fiesta amigo!<\/em>\u201d expres\u00f3 Paulina.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La chica dorada se une a uno de los programas mas famosos en la televisi\u00f3n en ingles, The X Factor. Simon Cowell estar\u00e1 rodeado de mujeres en la tercera temporada del programa The X Factor con las nuevas jueces Paulina Rubio y Kelly Rowland. \u201cMe ha tomado m\u00e1s de una d\u00e9cada, pero estoy encantado de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":5132,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6,368],"tags":[],"_links":{"self":[{"href":"http:\/\/paratodos.com\/pt\/wp-json\/wp\/v2\/posts\/5131"}],"collection":[{"href":"http:\/\/paratodos.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/paratodos.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/paratodos.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/paratodos.com\/pt\/wp-json\/wp\/v2\/comments?post=5131"}],"version-history":[{"count":1,"href":"http:\/\/paratodos.com\/pt\/wp-json\/wp\/v2\/posts\/5131\/revisions"}],"predecessor-version":[{"id":5133,"href":"http:\/\/paratodos.com\/pt\/wp-json\/wp\/v2\/posts\/5131\/revisions\/5133"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/paratodos.com\/pt\/wp-json\/wp\/v2\/media\/5132"}],"wp:attachment":[{"href":"http:\/\/paratodos.com\/pt\/wp-json\/wp\/v2\/media?parent=5131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/paratodos.com\/pt\/wp-json\/wp\/v2\/categories?post=5131"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/paratodos.com\/pt\/wp-json\/wp\/v2\/tags?post=5131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}